{"id":2167,"date":"2025-11-18T14:33:49","date_gmt":"2025-11-18T13:33:49","guid":{"rendered":"https:\/\/www.selectionmed.com\/agents\/catherine-portet"},"modified":"2025-11-18T14:40:16","modified_gmt":"2025-11-18T13:40:16","slug":"catherine-portet","status":"publish","type":"agents","link":"https:\/\/www.selectionmed.com\/fr\/agents\/catherine-portet","title":{"rendered":"Catherine Portet"},"content":{"rendered":"<p><strong>Un parcours guid\u00e9 par l&rsquo;\u00e9coute, l&rsquo;intuition et l&rsquo;exigence du service sur-mesure<\/strong><\/p>\n<p>Ma carri\u00e8re a d\u00e9but\u00e9 dans l&rsquo;univers du pr\u00eat-\u00e0-porter, o\u00f9 j&rsquo;\u00e9tais en charge de la s\u00e9lection des collections pour une grande enseigne. Cette premi\u00e8re exp\u00e9rience a \u00e9t\u00e9 fondatrice : elle m&rsquo;a permis de d\u00e9velopper un sens aigu de l&rsquo;\u00e9coute, une r\u00e9elle capacit\u00e9 \u00e0 cerner les besoins, et des talents de n\u00e9gociation que je n&rsquo;ai cess\u00e9 d&rsquo;affiner depuis.<\/p>\n<p>En 2002, mon installation dans le Sud a marqu\u00e9 un tournant d\u00e9cisif. J&rsquo;ai cr\u00e9\u00e9 mon activit\u00e9 de chasseur immobilier sur Valbonne et ses environs, r\u00e9pondant \u00e0 une demande croissante de services personnalis\u00e9s dans un march\u00e9 en pleine \u00e9volution. Depuis, j&rsquo;ai b\u00e2ti ann\u00e9e apr\u00e8s ann\u00e9e une connaissance fine et pr\u00e9cise du secteur, me permettant d&rsquo;accompagner aussi bien les vendeurs que les acqu\u00e9reurs avec rigueur, transparence et efficacit\u00e9.<\/p>\n<p>Toujours guid\u00e9e par les valeurs essentielles de ma profession \u2013 d\u00e9ontologie, probit\u00e9 et engagement \u2013, je m&rsquo;attache \u00e0 offrir \u00e0 chacun de mes clients un accompagnement sur mesure, fond\u00e9 sur la confiance et les r\u00e9sultats.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un parcours guid\u00e9 par l&rsquo;\u00e9coute, l&rsquo;intuition et l&rsquo;exigence du service sur-mesure Ma carri\u00e8re a d\u00e9but\u00e9 dans l&rsquo;univers du pr\u00eat-\u00e0-porter, o\u00f9 j&rsquo;\u00e9tais en charge de la s\u00e9lection des collections pour une grande enseigne. Cette premi\u00e8re exp\u00e9rience a \u00e9t\u00e9 fondatrice : elle m&rsquo;a permis de d\u00e9velopper un sens aigu de l&rsquo;\u00e9coute, une r\u00e9elle capacit\u00e9 \u00e0 cerner les &#8230;<\/p>\n","protected":false},"featured_media":2165,"template":"","class_list":["post-2167","agents","type-agents","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.selectionmed.com\/fr\/wp-json\/wp\/v2\/agents\/2167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.selectionmed.com\/fr\/wp-json\/wp\/v2\/agents"}],"about":[{"href":"https:\/\/www.selectionmed.com\/fr\/wp-json\/wp\/v2\/types\/agents"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.selectionmed.com\/fr\/wp-json\/wp\/v2\/media\/2165"}],"wp:attachment":[{"href":"https:\/\/www.selectionmed.com\/fr\/wp-json\/wp\/v2\/media?parent=2167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}